{"id":47017,"date":"2020-05-19T02:13:39","date_gmt":"2020-05-19T02:13:39","guid":{"rendered":"https:\/\/oksenlaw.com\/abogados\/"},"modified":"2026-07-02T18:53:04","modified_gmt":"2026-07-02T18:53:04","slug":"abogados","status":"publish","type":"page","link":"https:\/\/oksenlaw.com\/es\/abogados\/","title":{"rendered":"Abogados"},"content":{"rendered":"<p>En Oksenendler Law, P.C. en San Francisco, nuestro abogado s\u00e9nior Demi\u00e1n I. Oksenendler lleva m\u00e1s de 20 a\u00f1os enfrent\u00e1ndose a las compa\u00f1\u00edas de seguros en nombre de los consumidores del \u00c1rea de la Bah\u00eda.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre la trayectoria individual de nuestros abogados, siga los enlaces a continuaci\u00f3n.<\/p>\n<ul>\n<li><a href=\"https:\/\/oksenlaw.com\/es\/attorney\/oksenendler-demian-i\/\">Demi\u00e1n I. Oksenendler<\/a><\/li>\n<\/ul>\n<p>Estaremos encantados de resolver tus dudas. Por favor, <a href=\"https:\/\/oksenlaw.com\/es\/contacto\/\">env\u00edanos un correo electr\u00f3nico<\/a> hoy mismo o llama a nuestra oficina al <a role=\"link\" href=\"tel:+1-(415) 733-1050\" data-wpel-link=\"internal\">(415) 733-1050<\/a> para saber c\u00f3mo podemos ayudarte. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Oksenendler Law, P.C. en San Francisco, nuestro abogado s\u00e9nior Demi\u00e1n I. Oksenendler lleva m\u00e1s de 20 a\u00f1os enfrent\u00e1ndose a las compa\u00f1\u00edas de seguros en nombre de los consumidores del \u00c1rea de la Bah\u00eda. Para obtener m\u00e1s informaci\u00f3n sobre la trayectoria individual de nuestros abogados, siga los enlaces a continuaci\u00f3n. Demi\u00e1n I. Oksenendler Estaremos encantados [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-47017","page","type-page","status-publish","hentry"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/oksenlaw.com\/es\/wp-json\/wp\/v2\/pages\/47017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oksenlaw.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oksenlaw.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oksenlaw.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/oksenlaw.com\/es\/wp-json\/wp\/v2\/comments?post=47017"}],"version-history":[{"count":1,"href":"https:\/\/oksenlaw.com\/es\/wp-json\/wp\/v2\/pages\/47017\/revisions"}],"predecessor-version":[{"id":47245,"href":"https:\/\/oksenlaw.com\/es\/wp-json\/wp\/v2\/pages\/47017\/revisions\/47245"}],"wp:attachment":[{"href":"https:\/\/oksenlaw.com\/es\/wp-json\/wp\/v2\/media?parent=47017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}